{"id":163,"date":"2024-01-10T11:49:54","date_gmt":"2024-01-10T11:49:54","guid":{"rendered":"https:\/\/gurubhainews.com\/?page_id=163"},"modified":"2025-05-09T17:06:51","modified_gmt":"2025-05-09T17:06:51","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/gurubhainews.com\/index.php\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"163\" class=\"elementor elementor-163\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73f5626 e-con-full e-flex e-con e-parent\" data-id=\"73f5626\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-147d987 elementor-widget elementor-widget-text-editor\" data-id=\"147d987\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 24-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Registered Address: 1st Floor, C\/115, Infront Of Kids Care Hospital, Devendranagar, Sector-1, Raipur, Chhattisgarh, 492001<\/p><p>Email: info@gurubhainews.com<span class=\"header-title username\"><br \/><\/span>Phone: \u202a+<span class=\"xmi5d70 x1fvot60 xo1l8bm xxio538 xbsr9hj xq9mrsl x1h4wwuj xeuugli\">919301259672<\/span><\/p><p>GSTIN: 22AABCT6816H1ZI<\/p><div class=\"x1iyjqo2 xs83m0k xdl72j9 x3igimt xedcshv x1t2pt76 xyamay9 x1l90r2v x1swvt13 x1pi30zi x178xt8z x13fuv20 xwebqov xvyu6v8 xrsgblv x10lij0i\"><div class=\"x78zum5 xdt5ytf x1qughib xozqiw3 x2lwn1j xeuugli x1iyjqo2 xs83m0k xavht8x\">\u00a0<\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba3dde2 e-flex e-con-boxed e-con e-parent\" data-id=\"ba3dde2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ec7c4b elementor-widget elementor-widget-wpforms\" data-id=\"8ec7c4b\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style id=\"wpforms-css-vars-root\">\n\t\t\t\t:root {\n\t\t\t\t\t--wpforms-field-border-radius: 3px;\n--wpforms-field-background-color: #ffffff;\n--wpforms-field-border-color: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-text-color: rgba( 0, 0, 0, 0.7 );\n--wpforms-label-color: rgba( 0, 0, 0, 0.85 );\n--wpforms-label-sublabel-color: rgba( 0, 0, 0, 0.55 );\n--wpforms-label-error-color: #d63637;\n--wpforms-button-border-radius: 3px;\n--wpforms-button-background-color: #066aab;\n--wpforms-button-text-color: #ffffff;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\n\t\t\t\t}\n\t\t\t<\/style><style id=\"wpforms-css-vars-elementor-widget-8ec7c4b\">\n\t\t\t\t.elementor-widget-wpforms.elementor-element-8ec7c4b {\n\t\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\n\t\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-165\"><form id=\"wpforms-form-165\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"165\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/163\" data-token=\"a164daa3db990a84db4394fb7f85023c\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-165-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-165-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" aria-errormessage=\"wpforms-165-field_0-error\" required><label for=\"wpforms-165-field_0\" class=\"wpforms-field-sublabel after \">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-165-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" aria-errormessage=\"wpforms-165-field_0-last-error\" required><label for=\"wpforms-165-field_0-last\" class=\"wpforms-field-sublabel after \">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-165-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-165-field_1\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-165-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-165-field_1-error\" required><\/div><div id=\"wpforms-165-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-165-field_2\">Comment or Message<\/label><textarea id=\"wpforms-165-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-165-field_2-error\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"165\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"2\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-165\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"https:\/\/gurubhainews.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Registered Address: 1st Floor, C\/115, Infront Of Kids Care Hospital, Devendranagar, Sector-1, Raipur, Chhattisgarh, 492001 Email: info@gurubhainews.comPhone: \u202a+919301259672 GSTIN: 22AABCT6816H1ZI \u00a0 Please enable JavaScript in your browser to complete this form.Please enable JavaScript in your browser to complete this form. Name * FirstLast Email *Comment or Message Submit<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-163","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/gurubhainews.com\/index.php\/wp-json\/wp\/v2\/pages\/163"}],"collection":[{"href":"https:\/\/gurubhainews.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gurubhainews.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gurubhainews.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gurubhainews.com\/index.php\/wp-json\/wp\/v2\/comments?post=163"}],"version-history":[{"count":7,"href":"https:\/\/gurubhainews.com\/index.php\/wp-json\/wp\/v2\/pages\/163\/revisions"}],"predecessor-version":[{"id":3076,"href":"https:\/\/gurubhainews.com\/index.php\/wp-json\/wp\/v2\/pages\/163\/revisions\/3076"}],"wp:attachment":[{"href":"https:\/\/gurubhainews.com\/index.php\/wp-json\/wp\/v2\/media?parent=163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}